{"id":1185,"date":"2018-08-31T17:19:39","date_gmt":"2018-08-31T20:19:39","guid":{"rendered":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/perfil-del-egresado\/"},"modified":"2018-08-31T17:19:39","modified_gmt":"2018-08-31T20:19:39","slug":"perfil-del-egresado","status":"publish","type":"page","link":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/perfil-del-egresado\/","title":{"rendered":"Perfil del Egresado"},"content":{"rendered":"<p><span style=\"font-family: arial black,avant garde; color: #800080;\">&nbsp;PERFIL DEL EGRESADO<\/span><\/p>\n<p style=\"text-align: justify;\">La Formaci&oacute;n Docente en Lengua y Literatura aspira a formar egresados que desarrollen&nbsp; m&uacute;ltiples capacidades intelectuales, pr&aacute;cticas y sociales, que les permitan acompa&ntilde;ar de modo &oacute;ptimo el desarrollo de sus alumnos, lo que requiere:<\/p>\n<ul type=\"disc\">\n<li style=\"text-align: justify;\">Dominar los conocimientos ling&uuml;&iacute;sticos y literarios que hacen posible tomar&nbsp; decisiones, orientar y evaluar procesos en la ense&ntilde;anza de la lengua y la literatura, atendiendo a las singularidades de la Educaci&oacute;n Secundaria y a la diversidad de contextos.<\/li>\n<li style=\"text-align: justify;\">Analizar los procesos socio-hist&oacute;ricos de producci&oacute;n de conocimiento propios de los campos de la Lengua y la Literatura, reflexionando sobre sus especificidades y mutuas &nbsp;relaciones.<\/li>\n<li style=\"text-align: justify;\">Identificar las caracter&iacute;sticas y necesidades de aprendizaje de los alumnos como base para&nbsp; su&nbsp; actuaci&oacute;n docente.<\/li>\n<li style=\"text-align: justify;\">Asumir la actividad docente como una pr&aacute;ctica social transformadora, que se sostiene en valores democr&aacute;ticos y que revaloriza el conocimiento como herramienta&nbsp; necesaria para comprender y transformar la realidad.<\/li>\n<li style=\"text-align: justify;\">Logren una mirada investigativa y anal&iacute;tica en torno a la pr&aacute;ctica docente que le permitan organizar y dirigir situaciones de aprendizaje, utilizando al contexto sociopol&iacute;tico, sociocultural y socioling&uuml;&iacute;stico como fuente de ense&ntilde;anza.<\/li>\n<li style=\"text-align: justify;\">Comprender la multiplicidad y complejidad de las maneras en que lo escrito, lo oral, lo gestual y lo audiovisual articulan nuevos modos de leer y escribir y se integran en sistemas de hipertextos accesibles en Internet y la red mundial y c&oacute;mo esto puede entrelazarse con la cultura del libro, del texto impreso y la interacci&oacute;n humana, sin que suponga la expulsi&oacute;n de uno u otro soporte.<\/li>\n<li style=\"text-align: justify;\">Manejar saberes relacionados con las Tecnolog&iacute;as de la Informaci&oacute;n y de la Comunicaci&oacute;n&nbsp; que&nbsp; favorezcan&nbsp; una&nbsp; lectura&nbsp; cr&iacute;tica&nbsp; en&nbsp; tanto&nbsp; practicas&nbsp; sociales,&nbsp; &nbsp;su problematizaci&oacute;n did&aacute;ctica y sus implicancias en la l&oacute;gica de producci&oacute;n del conocimiento&nbsp; cient&iacute;fico.<\/li>\n<li style=\"text-align: justify;\">Tomar decisiones sobre la administraci&oacute;n de los tiempos y el ambiente del aula para permitir el logro de aprendizajes del conjunto de los alumnos.<\/li>\n<li style=\"text-align: justify;\">Conducir los procesos grupales y facilitar el aprendizaje individual.<\/li>\n<li style=\"text-align: justify;\">Reconocer y utilizar los recursos disponibles en la escuela para su aprovechamiento en la ense&ntilde;anza.<\/li>\n<li style=\"text-align: justify;\">Participar en el intercambio y comunicaci&oacute;n con las familias para retroalimentar su propia tarea.<\/li>\n<li style=\"text-align: justify;\">Trabajar&nbsp;&nbsp;&nbsp;&nbsp; en&nbsp;&nbsp;&nbsp;&nbsp; equipo&nbsp;&nbsp;&nbsp;&nbsp; con&nbsp;&nbsp;&nbsp;&nbsp; otros&nbsp;&nbsp;&nbsp;&nbsp; docentes,&nbsp;&nbsp;&nbsp;&nbsp; elaborar&nbsp;&nbsp;&nbsp;&nbsp; proyectos&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; institucionales compartidos y participar y proponer actividades propias de la escuela.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;PERFIL DEL EGRESADO La Formaci&oacute;n Docente en Lengua y Literatura aspira a formar egresados que desarrollen&nbsp; m&uacute;ltiples capacidades intelectuales, pr&aacute;cticas y sociales, que les permitan acompa&ntilde;ar de modo &oacute;ptimo el desarrollo de sus alumnos, lo que requiere: Dominar los conocimientos ling&uuml;&iacute;sticos y literarios que hacen posible tomar&nbsp; decisiones, orientar y evaluar procesos en la ense&ntilde;anza &#8230; <a title=\"Perfil del Egresado\" class=\"read-more\" href=\"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/perfil-del-egresado\/\" aria-label=\"More on Perfil del Egresado\">[+]<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/1185"}],"collection":[{"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":0,"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/1185\/revisions"}],"wp:attachment":[{"href":"https:\/\/ifd3-sgo.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}